{"id":47153,"date":"2026-07-13T18:11:22","date_gmt":"2026-07-13T18:11:22","guid":{"rendered":"https:\/\/apuntmenorca.com\/?p=47153"},"modified":"2026-07-13T18:11:22","modified_gmt":"2026-07-13T18:11:22","slug":"cicle-de-jazz-es-claustre-2026-apuesta-por-la-proyeccion-internacional","status":"publish","type":"post","link":"https:\/\/apuntmenorca.com\/ca\/actualitat\/cicle-de-jazz-es-claustre-2026-apuesta-por-la-proyeccion-internacional\/","title":{"rendered":"El cicle de jazz Es Claustre 23 creix en projecci\u00f3 internacional"},"content":{"rendered":"<p class=\"isSelectedEnd\">El <strong>Cicle de Jazz Es Claustre 23<\/strong> torna la temporada 2026 amb una edici\u00f3 que referma la seva posici\u00f3 com <strong>una de les cites imprescindibles del jazz a Balears<\/strong>.<\/p>\n<p class=\"isSelectedEnd\">Sota la direcci\u00f3 art\u00edstica de Juan Pablo Balc\u00e1zar, programador de la sala barcelonina Robadors 23, el cicle mant\u00e9 la seva ess\u00e8ncia dominical i l&#8217;aposta per la qualitat, alhora que fa <strong>un pas decidit cap a la internacionalitzaci\u00f3<\/strong>.<\/p>\n<h2>Els primers concerts d&#8217;Es Claustre 23, amb accent local<\/h2>\n<p class=\"isSelectedEnd\">El cicle arrenca el 3 de maig amb el <strong>Guiem Pons Elation Trio<\/strong>, en una inauguraci\u00f3 que posa en relleu el protagonisme de l&#8217;escena menorquina i balear durant les primeres setmanes. El mes de maig continua amb <strong>Dani \u00c1lvarez feat. Gorka Ben\u00edtez<\/strong> (10 de maig), <strong>Arecio Smith<\/strong> (17 de maig), <strong>Carolina Merlo &amp; Antonio Mazzei<\/strong> (24 de maig) i <strong>Gigi McFarlane<\/strong> (31 de maig).<\/p>\n<p class=\"isSelectedEnd\">El juny mant\u00e9 aquesta mateixa l\u00ednia amb formacions com el <strong>Mart\u00ed Genestar Trio<\/strong> (14 de juny), <strong>Fran Ramos<\/strong> (21 de juny) i el <strong>Pere Bujosa Trio<\/strong> (28 de juny). La gran excepci\u00f3 del mes \u00e9s el Richard Bona Trio (7 de juny), una refer\u00e8ncia indiscutible del jazz internacional que eleva el nivell del cartell abans del gir internacional de l&#8217;estiu.<\/p>\n<h2>Un gir internacional a partir del juliol<\/h2>\n<p>El juliol marca un punt d&#8217;inflexi\u00f3. <strong>Deborah Carter<\/strong> inaugura el mes, el 5 de juliol, amb un homenatge a Ella Fitzgerald, i el 8 de juliol passa per Es Claustre <strong>Milena Casado<\/strong>, trompetista d&#8217;Osca establerta a Nova York, considerada una \u00abrevelaci\u00f3\u00bb per The New York Times i Los Angeles Times. Tot i comptar amb un \u00fanic disc publicat, <em>Reflection of Another Self<\/em>, ja ha actuat en escenaris tan prestigiosos com el Carnegie Hall, el Village Vanguard o el North Sea Jazz Festival.<\/p>\n<p class=\"isSelectedEnd\">La resta del mes mant\u00e9 el mateix nivell d&#8217;exig\u00e8ncia amb el pianista nord-americ\u00e0 <strong>Rob Clearfield<\/strong> (12 de juliol) i el saxofonista <strong>Perico Sambeat<\/strong> (19 de juliol), un dels m\u00fasics m\u00e9s destacats del jazz europeu. El tancament de juliol anir\u00e0 a c\u00e0rrec de <strong>Juana Gait\u00e1n<\/strong> (26 de juliol) i el seu projecte <em>Jazz Colombia<\/em>, que aportar\u00e0 una mirada llatinoamericana al cicle.<\/p>\n<p class=\"isSelectedEnd\">L&#8217;agost mant\u00e9 aquesta vocaci\u00f3 internacional amb <strong>Anggie Obin<\/strong> (2 d&#8217;agost) i el m\u00fasic suec <strong>Gustav Lundgren Trio<\/strong> (9 d&#8217;agost), un dels guitarristes m\u00e9s reconeguts d&#8217;Europa. El moment central del mes arribar\u00e0 el 16 d&#8217;agost amb el <strong>Jean Toussaint Quartet<\/strong>, figura hist\u00f2rica del jazz contemporani que torna a Es Claustre despr\u00e9s de l&#8217;\u00e8xit de l&#8217;any passat.<\/p>\n<p class=\"isSelectedEnd\">La cloenda del cicle ser\u00e0 el 23 d&#8217;agost amb <strong>Eva Fern\u00e1ndez<\/strong>, compositora, saxofonista i cantant formada a l&#8217;escola Joan Chamorro i una de les artistes amb m\u00e9s projecci\u00f3 del panorama estatal.<\/p>\n<h2>Una programaci\u00f3 amb la mirada posada en la paritat<\/h2>\n<p class=\"isSelectedEnd\">Un dels trets distintius d&#8217;aquesta edici\u00f3 \u00e9s <strong>la voluntat d&#8217;avan\u00e7ar cap a una programaci\u00f3 m\u00e9s equilibrada pel que fa a la pres\u00e8ncia de dones<\/strong>. \u00abDurant els primers mesos no ha estat f\u00e0cil assolir aquesta paritat dins l&#8217;escena local\u00bb, reconeix Balc\u00e1zar, \u00abper\u00f2, en canvi, les grans cites del juliol i l&#8217;agost estan clarament liderades per artistes de primer nivell\u00bb.<\/p>\n<p>Amb aquesta nova edici\u00f3, Es Claustre confirma que <strong>el jazz a Menorca no \u00e9s una aposta puntual, sin\u00f3 un projecte amb recorregut, criteri i vocaci\u00f3 de continu\u00eftat<\/strong>. Un cicle que ha sabut cr\u00e9ixer sense perdre la seva ess\u00e8ncia: dominical, accessible i amb el Pati des Claustre del Carme com a escenari insubstitu\u00efble.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Cicle de Jazz Es Claustre 23 torna la temporada 2026 amb una edici\u00f3 que referma la seva posici\u00f3 com una de les cites imprescindibles del jazz a Balears. Sota la direcci\u00f3 art\u00edstica de Juan Pablo Balc\u00e1zar, programador de la sala barcelonina Robadors 23, el cicle mant\u00e9 la seva ess\u00e8ncia dominical i l&#8217;aposta per la [&#8230;]\n","protected":false},"author":8,"featured_media":47007,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[525],"tags":[594],"class_list":["post-47153","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualitat","tag-cicle-de-jazz-es-claustre-23"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.1 (Yoast SEO v27.1.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El cicle de jazz Es Claustre 23 creix en projecci\u00f3 internacional<\/title>\n<meta name=\"description\" content=\"El cicle de jazz d&#039;Es Claustre torna en 2026 amb una edici\u00f3 que reaferma la seva posici\u00f3 com una de les cites imprescindibles del jazz.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/apuntmenorca.com\/ca\/actualitat\/cicle-de-jazz-es-claustre-2026-apuesta-por-la-proyeccion-internacional\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El cicle de jazz Es Claustre 23 creix en projecci\u00f3 internacional\" \/>\n<meta property=\"og:description\" content=\"El cicle de jazz d&#039;Es Claustre torna en 2026 amb una edici\u00f3 que reaferma la seva posici\u00f3 com una de les cites imprescindibles del jazz.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/apuntmenorca.com\/ca\/actualitat\/cicle-de-jazz-es-claustre-2026-apuesta-por-la-proyeccion-internacional\/\" \/>\n<meta property=\"og:site_name\" content=\"apuntmenorca.com\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-13T18:11:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/apuntmenorca.com\/wp-content\/uploads\/2026\/07\/ESDEVENIMENT-16-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1020\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Araceli Florit\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Araceli Florit\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/apuntmenorca.com\/ca\/actualitat\/cicle-de-jazz-es-claustre-2026-apuesta-por-la-proyeccion-internacional\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/apuntmenorca.com\/ca\/actualitat\/cicle-de-jazz-es-claustre-2026-apuesta-por-la-proyeccion-internacional\/\"},\"author\":{\"name\":\"Araceli Florit\",\"@id\":\"https:\/\/apuntmenorca.com\/#\/schema\/person\/479134fad922c810c8f12d67a1e91597\"},\"headline\":\"El cicle de jazz Es Claustre 23 creix en projecci\u00f3 internacional\",\"datePublished\":\"2026-07-13T18:11:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/apuntmenorca.com\/ca\/actualitat\/cicle-de-jazz-es-claustre-2026-apuesta-por-la-proyeccion-internacional\/\"},\"wordCount\":587,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/apuntmenorca.com\/ca\/actualitat\/cicle-de-jazz-es-claustre-2026-apuesta-por-la-proyeccion-internacional\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/apuntmenorca.com\/wp-content\/uploads\/2026\/07\/ESDEVENIMENT-16-1.png\",\"keywords\":[\"Cicle de Jazz Es Claustre 23\"],\"articleSection\":[\"Actualitat\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/apuntmenorca.com\/ca\/actualitat\/cicle-de-jazz-es-claustre-2026-apuesta-por-la-proyeccion-internacional\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/apuntmenorca.com\/ca\/actualitat\/cicle-de-jazz-es-claustre-2026-apuesta-por-la-proyeccion-internacional\/\",\"url\":\"https:\/\/apuntmenorca.com\/ca\/actualitat\/cicle-de-jazz-es-claustre-2026-apuesta-por-la-proyeccion-internacional\/\",\"name\":\"El cicle de jazz Es Claustre 23 creix en projecci\u00f3 internacional\",\"isPartOf\":{\"@id\":\"https:\/\/apuntmenorca.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/apuntmenorca.com\/ca\/actualitat\/cicle-de-jazz-es-claustre-2026-apuesta-por-la-proyeccion-internacional\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/apuntmenorca.com\/ca\/actualitat\/cicle-de-jazz-es-claustre-2026-apuesta-por-la-proyeccion-internacional\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/apuntmenorca.com\/wp-content\/uploads\/2026\/07\/ESDEVENIMENT-16-1.png\",\"datePublished\":\"2026-07-13T18:11:22+00:00\",\"author\":{\"@id\":\"https:\/\/apuntmenorca.com\/#\/schema\/person\/479134fad922c810c8f12d67a1e91597\"},\"description\":\"El cicle de jazz d'Es Claustre torna en 2026 amb una edici\u00f3 que reaferma la seva posici\u00f3 com una de les cites imprescindibles del jazz.\",\"breadcrumb\":{\"@id\":\"https:\/\/apuntmenorca.com\/ca\/actualitat\/cicle-de-jazz-es-claustre-2026-apuesta-por-la-proyeccion-internacional\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/apuntmenorca.com\/ca\/actualitat\/cicle-de-jazz-es-claustre-2026-apuesta-por-la-proyeccion-internacional\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/apuntmenorca.com\/ca\/actualitat\/cicle-de-jazz-es-claustre-2026-apuesta-por-la-proyeccion-internacional\/#primaryimage\",\"url\":\"https:\/\/apuntmenorca.com\/wp-content\/uploads\/2026\/07\/ESDEVENIMENT-16-1.png\",\"contentUrl\":\"https:\/\/apuntmenorca.com\/wp-content\/uploads\/2026\/07\/ESDEVENIMENT-16-1.png\",\"width\":1800,\"height\":1020,\"caption\":\"Cicle de Jazz Es Claustre 23\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/apuntmenorca.com\/ca\/actualitat\/cicle-de-jazz-es-claustre-2026-apuesta-por-la-proyeccion-internacional\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/apuntmenorca.com\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El cicle de jazz Es Claustre 23 creix en projecci\u00f3 internacional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/apuntmenorca.com\/#website\",\"url\":\"https:\/\/apuntmenorca.com\/\",\"name\":\"apuntmenorca.com\",\"description\":\"Menorca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/apuntmenorca.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/apuntmenorca.com\/#\/schema\/person\/479134fad922c810c8f12d67a1e91597\",\"name\":\"Araceli Florit\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/apuntmenorca.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93c4435c97221360f8a450b9cb505e9004b0dac97f603f641408763f9a504724?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93c4435c97221360f8a450b9cb505e9004b0dac97f603f641408763f9a504724?s=96&d=mm&r=g\",\"caption\":\"Araceli Florit\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El cicle de jazz Es Claustre 23 creix en projecci\u00f3 internacional","description":"El cicle de jazz d'Es Claustre torna en 2026 amb una edici\u00f3 que reaferma la seva posici\u00f3 com una de les cites imprescindibles del jazz.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/apuntmenorca.com\/ca\/actualitat\/cicle-de-jazz-es-claustre-2026-apuesta-por-la-proyeccion-internacional\/","og_locale":"ca_ES","og_type":"article","og_title":"El cicle de jazz Es Claustre 23 creix en projecci\u00f3 internacional","og_description":"El cicle de jazz d'Es Claustre torna en 2026 amb una edici\u00f3 que reaferma la seva posici\u00f3 com una de les cites imprescindibles del jazz.","og_url":"https:\/\/apuntmenorca.com\/ca\/actualitat\/cicle-de-jazz-es-claustre-2026-apuesta-por-la-proyeccion-internacional\/","og_site_name":"apuntmenorca.com","article_published_time":"2026-07-13T18:11:22+00:00","og_image":[{"width":1800,"height":1020,"url":"https:\/\/apuntmenorca.com\/wp-content\/uploads\/2026\/07\/ESDEVENIMENT-16-1.png","type":"image\/png"}],"author":"Araceli Florit","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"Araceli Florit","Temps estimat de lectura":"4 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/apuntmenorca.com\/ca\/actualitat\/cicle-de-jazz-es-claustre-2026-apuesta-por-la-proyeccion-internacional\/#article","isPartOf":{"@id":"https:\/\/apuntmenorca.com\/ca\/actualitat\/cicle-de-jazz-es-claustre-2026-apuesta-por-la-proyeccion-internacional\/"},"author":{"name":"Araceli Florit","@id":"https:\/\/apuntmenorca.com\/#\/schema\/person\/479134fad922c810c8f12d67a1e91597"},"headline":"El cicle de jazz Es Claustre 23 creix en projecci\u00f3 internacional","datePublished":"2026-07-13T18:11:22+00:00","mainEntityOfPage":{"@id":"https:\/\/apuntmenorca.com\/ca\/actualitat\/cicle-de-jazz-es-claustre-2026-apuesta-por-la-proyeccion-internacional\/"},"wordCount":587,"commentCount":0,"image":{"@id":"https:\/\/apuntmenorca.com\/ca\/actualitat\/cicle-de-jazz-es-claustre-2026-apuesta-por-la-proyeccion-internacional\/#primaryimage"},"thumbnailUrl":"https:\/\/apuntmenorca.com\/wp-content\/uploads\/2026\/07\/ESDEVENIMENT-16-1.png","keywords":["Cicle de Jazz Es Claustre 23"],"articleSection":["Actualitat"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/apuntmenorca.com\/ca\/actualitat\/cicle-de-jazz-es-claustre-2026-apuesta-por-la-proyeccion-internacional\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/apuntmenorca.com\/ca\/actualitat\/cicle-de-jazz-es-claustre-2026-apuesta-por-la-proyeccion-internacional\/","url":"https:\/\/apuntmenorca.com\/ca\/actualitat\/cicle-de-jazz-es-claustre-2026-apuesta-por-la-proyeccion-internacional\/","name":"El cicle de jazz Es Claustre 23 creix en projecci\u00f3 internacional","isPartOf":{"@id":"https:\/\/apuntmenorca.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/apuntmenorca.com\/ca\/actualitat\/cicle-de-jazz-es-claustre-2026-apuesta-por-la-proyeccion-internacional\/#primaryimage"},"image":{"@id":"https:\/\/apuntmenorca.com\/ca\/actualitat\/cicle-de-jazz-es-claustre-2026-apuesta-por-la-proyeccion-internacional\/#primaryimage"},"thumbnailUrl":"https:\/\/apuntmenorca.com\/wp-content\/uploads\/2026\/07\/ESDEVENIMENT-16-1.png","datePublished":"2026-07-13T18:11:22+00:00","author":{"@id":"https:\/\/apuntmenorca.com\/#\/schema\/person\/479134fad922c810c8f12d67a1e91597"},"description":"El cicle de jazz d'Es Claustre torna en 2026 amb una edici\u00f3 que reaferma la seva posici\u00f3 com una de les cites imprescindibles del jazz.","breadcrumb":{"@id":"https:\/\/apuntmenorca.com\/ca\/actualitat\/cicle-de-jazz-es-claustre-2026-apuesta-por-la-proyeccion-internacional\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/apuntmenorca.com\/ca\/actualitat\/cicle-de-jazz-es-claustre-2026-apuesta-por-la-proyeccion-internacional\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/apuntmenorca.com\/ca\/actualitat\/cicle-de-jazz-es-claustre-2026-apuesta-por-la-proyeccion-internacional\/#primaryimage","url":"https:\/\/apuntmenorca.com\/wp-content\/uploads\/2026\/07\/ESDEVENIMENT-16-1.png","contentUrl":"https:\/\/apuntmenorca.com\/wp-content\/uploads\/2026\/07\/ESDEVENIMENT-16-1.png","width":1800,"height":1020,"caption":"Cicle de Jazz Es Claustre 23"},{"@type":"BreadcrumbList","@id":"https:\/\/apuntmenorca.com\/ca\/actualitat\/cicle-de-jazz-es-claustre-2026-apuesta-por-la-proyeccion-internacional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/apuntmenorca.com\/ca\/"},{"@type":"ListItem","position":2,"name":"El cicle de jazz Es Claustre 23 creix en projecci\u00f3 internacional"}]},{"@type":"WebSite","@id":"https:\/\/apuntmenorca.com\/#website","url":"https:\/\/apuntmenorca.com\/","name":"apuntmenorca.com","description":"Menorca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/apuntmenorca.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Person","@id":"https:\/\/apuntmenorca.com\/#\/schema\/person\/479134fad922c810c8f12d67a1e91597","name":"Araceli Florit","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/apuntmenorca.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/93c4435c97221360f8a450b9cb505e9004b0dac97f603f641408763f9a504724?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93c4435c97221360f8a450b9cb505e9004b0dac97f603f641408763f9a504724?s=96&d=mm&r=g","caption":"Araceli Florit"}}]}},"_links":{"self":[{"href":"https:\/\/apuntmenorca.com\/ca\/wp-json\/wp\/v2\/posts\/47153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apuntmenorca.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/apuntmenorca.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/apuntmenorca.com\/ca\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/apuntmenorca.com\/ca\/wp-json\/wp\/v2\/comments?post=47153"}],"version-history":[{"count":2,"href":"https:\/\/apuntmenorca.com\/ca\/wp-json\/wp\/v2\/posts\/47153\/revisions"}],"predecessor-version":[{"id":47155,"href":"https:\/\/apuntmenorca.com\/ca\/wp-json\/wp\/v2\/posts\/47153\/revisions\/47155"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/apuntmenorca.com\/ca\/wp-json\/wp\/v2\/media\/47007"}],"wp:attachment":[{"href":"https:\/\/apuntmenorca.com\/ca\/wp-json\/wp\/v2\/media?parent=47153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/apuntmenorca.com\/ca\/wp-json\/wp\/v2\/categories?post=47153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/apuntmenorca.com\/ca\/wp-json\/wp\/v2\/tags?post=47153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}